{"id":2195,"date":"2024-03-02T10:28:07","date_gmt":"2024-03-02T09:28:07","guid":{"rendered":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/"},"modified":"2024-06-21T11:21:01","modified_gmt":"2024-06-21T09:21:01","slug":"chic-chic-scrunchies-white-dragon","status":"publish","type":"product","link":"https:\/\/www.gentleaf.com\/es\/prodotto\/chic-chic-scrunchies-white-dragon\/","title":{"rendered":"CHIC CHIC Scrunchies &#8211; White Dragon"},"content":{"rendered":"<p>La seda vegana es una verdadera joya en el mundo textil. Un tejido fant\u00e1stico, ligero y fresco, transpirable, ecol\u00f3gico, derivado de fibras de celulosa vegetal, antiest\u00e1tico (disminuye la carga electrost\u00e1tica), el\u00e1stico, resistente y certificado Oeko Tex.<\/p>\n<p>Las fibras cortas que envuelven la semilla del algod\u00f3n (linter) son de pura celulosa. Gracias a un proceso ecol\u00f3gico y sustentable se transforman, dando vida a este incre\u00edble tejido, libre de sustancias t\u00f3xicas para el ser humano y el medio ambiente.<br \/>\nSus caracter\u00edsticas principales son una gran suavidad en la piel y el cabello, adem\u00e1s de una hermosa luminosidad que lo hace similar a la seda. La fibra tiene una secci\u00f3n circular y una superficie muy lisa, m\u00e1s suave que el algod\u00f3n y muchas otras fibras, tanto naturales como sint\u00e9ticas, por lo que es muy agradable en la piel y no causa irritaciones por fricci\u00f3n. Por la misma raz\u00f3n, los detergentes utilizados para lavar estos tejidos se deslizan y no se sedimentan, por lo que tambi\u00e9n se reduce al m\u00ednimo el riesgo de alergias derivadas de las sustancias utilizadas para lavarlos.<\/p>\n<p>\u00a1\u00a1\u00a1Pero eso no es todo!!! La fibra de celulosa absorbe f\u00e1cilmente la humedad y la libera al exterior. Esto hace que los tejidos de seda vegetal sean muy transpirables y especialmente agradables.<\/p>\n<p>A estas fant\u00e1sticas propiedades le sumamos su biodegradabilidad y adaptabilidad a multitud de usos. A nosotros especialmente nos encanta cuidar nuestro cabello y esta tela es perfecta, cubre todas nuestras necesidades. Hemos podido comprobar que no se desliza, cada scrunchie permanece en su lugar durante horas y horas, \u00a1sin tirar ni romper el cabello! Ll\u00e9valo siempre contigo y, cuando lo necesites, un simple recogido en cola de caballo o un chignon improvisado ser\u00e1n perfectos y s\u00faper chic!<\/p>\n<p>Consejo: \u00a1\u00fasalo por la noche para hacer la\u00bbpi\u00f1a\u00bb y salvar tu cabello de perder definici\u00f3n y prevenir el encrespamiento! ;)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El drag\u00f3n es un s\u00edmbolo de fuerza, de poder, una figura mitol\u00f3gica muy presente en las leyendas del Oriente. El blanco est\u00e1 asociado con la transici\u00f3n de la vida a la muerte, as\u00ed como con la pureza y la paz. El drag\u00f3n representa la sabidur\u00eda, la fuerza vital y la fertilidad, as\u00ed como el agua y la lluvia; \u00e9l es quien trae la lluvia (ben\u00e9fica). De hecho, se representa entre las nubes.<\/p>\n<p>A\u00f1ade un toque de elegancia, color y luz a tu peinado.<br \/>\nCHIC CHIC es una l\u00ednea de accesorios para el cabello creada por nuestro equipo y fabricada completamente a mano por mujeres artesanas, en respeto al trabajo, los peque\u00f1os n\u00fameros y la solidaridad. Las peque\u00f1as tiradas, la singularidad de cada pieza y el alto est\u00e1ndar de calidad de los tejidos utilizados hacen que este producto sea realmente especial.<\/p>\n<div class=\"flex flex-grow flex-col max-w-full\">\n<div class=\"min-h-[20px] text-message flex flex-col items-start whitespace-pre-wrap break-words [.text-message+&amp;]:mt-5 juice:w-full juice:items-end overflow-x-auto gap-2\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"ab97075d-697a-44f5-a144-9104db1b43cc\">\n<div class=\"flex w-full flex-col gap-1 juice:empty:hidden juice:first:pt-[3px]\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Los scrunchies CHIC CHIC son de seda vegana, derivada de celulosa, cruelty-free, biodegradables y s\u00faper transpirables. Un tejido de alta calidad fant\u00e1stico para el cabello. Suaves como una nube y delicados, no rompen el cabello ni lo cargan de electricidad est\u00e1tica.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1528\" src=\"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/12\/prodotto-artigianale.svg\" alt=\"\" width=\"100\" height=\"100\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1526\" src=\"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/12\/made-in-italy.svg\" alt=\"\" width=\"100\" height=\"100\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1527\" src=\"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/12\/pack-riciclabile.svg\" alt=\"\" width=\"100\" height=\"100\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1525\" src=\"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/12\/hand-made-with-love.svg\" alt=\"\" width=\"100\" height=\"100\" \/><img decoding=\"async\" class=\"alignnone wp-image-833\" src=\"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/02\/100-vegano.svg\" alt=\"\" width=\"100\" \/><\/p>\n","protected":false},"featured_media":2196,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"pwb-brand":[171],"product_brand":[],"product_cat":[196],"product_tag":[],"class_list":["post-2195","product","type-product","status-publish","has-post-thumbnail","pwb-brand-korean-hcr","product_cat-accesorios","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CHIC CHIC Scrunchies - White Dragon - Gentleaf<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHIC CHIC Scrunchies - White Dragon - Gentleaf\" \/>\n<meta property=\"og:description\" content=\"El drag\u00f3n es un s\u00edmbolo de fuerza, de poder, una figura mitol\u00f3gica muy presente en las leyendas del Oriente. El blanco est\u00e1 asociado con la transici\u00f3n de la vida a la muerte, as\u00ed como con la pureza y la paz. El drag\u00f3n representa la sabidur\u00eda, la fuerza vital y la fertilidad, as\u00ed como el agua y la lluvia; \u00e9l es quien trae la lluvia (ben\u00e9fica). De hecho, se representa entre las nubes.  A\u00f1ade un toque de elegancia, color y luz a tu peinado. CHIC CHIC es una l\u00ednea de accesorios para el cabello creada por nuestro equipo y fabricada completamente a mano por mujeres artesanas, en respeto al trabajo, los peque\u00f1os n\u00fameros y la solidaridad. Las peque\u00f1as tiradas, la singularidad de cada pieza y el alto est\u00e1ndar de calidad de los tejidos utilizados hacen que este producto sea realmente especial.      Los scrunchies CHIC CHIC son de seda vegana, derivada de celulosa, cruelty-free, biodegradables y s\u00faper transpirables. Un tejido de alta calidad fant\u00e1stico para el cabello. Suaves como una nube y delicados, no rompen el cabello ni lo cargan de electricidad est\u00e1tica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/\" \/>\n<meta property=\"og:site_name\" content=\"Gentleaf\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T09:21:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/02\/chic-chic-white.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/\",\"url\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/\",\"name\":\"CHIC CHIC Scrunchies - White Dragon - Gentleaf\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gentleaf.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/chic-chic-white.webp\",\"datePublished\":\"2024-03-02T09:28:07+00:00\",\"dateModified\":\"2024-06-21T09:21:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gentleaf.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/chic-chic-white.webp\",\"contentUrl\":\"https:\\\/\\\/www.gentleaf.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/chic-chic-white.webp\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/prodotto\\\/chic-chic-scrunchies-white-dragon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gentleaf.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.gentleaf.com\\\/es\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CHIC CHIC Scrunchies &#8211; White Dragon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/#website\",\"url\":\"https:\\\/\\\/www.gentleaf.com\\\/\",\"name\":\"Gentleaf\",\"description\":\"Organic professional cosmetics\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gentleaf.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/#organization\",\"name\":\"Gentleaf\",\"url\":\"https:\\\/\\\/www.gentleaf.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gentleaf.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/biogentleaf-logo-head.svg\",\"contentUrl\":\"https:\\\/\\\/www.gentleaf.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/biogentleaf-logo-head.svg\",\"width\":100,\"height\":100,\"caption\":\"Gentleaf\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gentleaf.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/gentleaf_bio\\\/?fbclid=IwY2xjawKBnY5leHRuA2FlbQIxMABicmlkETFnR3FwYjZ4RGRtRFJjamp2AR4SGdGOPrfdrVW-SGgGqLeTEuWwIANOXw19d6-WwnRUnESn5A7nOSsg73FS5A_aem_8xfPJYhVFMj_7_V1SzFGbg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CHIC CHIC Scrunchies - White Dragon - Gentleaf","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/","og_locale":"es_ES","og_type":"article","og_title":"CHIC CHIC Scrunchies - White Dragon - Gentleaf","og_description":"El drag\u00f3n es un s\u00edmbolo de fuerza, de poder, una figura mitol\u00f3gica muy presente en las leyendas del Oriente. El blanco est\u00e1 asociado con la transici\u00f3n de la vida a la muerte, as\u00ed como con la pureza y la paz. El drag\u00f3n representa la sabidur\u00eda, la fuerza vital y la fertilidad, as\u00ed como el agua y la lluvia; \u00e9l es quien trae la lluvia (ben\u00e9fica). De hecho, se representa entre las nubes.  A\u00f1ade un toque de elegancia, color y luz a tu peinado. CHIC CHIC es una l\u00ednea de accesorios para el cabello creada por nuestro equipo y fabricada completamente a mano por mujeres artesanas, en respeto al trabajo, los peque\u00f1os n\u00fameros y la solidaridad. Las peque\u00f1as tiradas, la singularidad de cada pieza y el alto est\u00e1ndar de calidad de los tejidos utilizados hacen que este producto sea realmente especial.      Los scrunchies CHIC CHIC son de seda vegana, derivada de celulosa, cruelty-free, biodegradables y s\u00faper transpirables. Un tejido de alta calidad fant\u00e1stico para el cabello. Suaves como una nube y delicados, no rompen el cabello ni lo cargan de electricidad est\u00e1tica.","og_url":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/","og_site_name":"Gentleaf","article_modified_time":"2024-06-21T09:21:01+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/02\/chic-chic-white.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/","url":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/","name":"CHIC CHIC Scrunchies - White Dragon - Gentleaf","isPartOf":{"@id":"https:\/\/www.gentleaf.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/#primaryimage"},"image":{"@id":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/02\/chic-chic-white.webp","datePublished":"2024-03-02T09:28:07+00:00","dateModified":"2024-06-21T09:21:01+00:00","breadcrumb":{"@id":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/#primaryimage","url":"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/02\/chic-chic-white.webp","contentUrl":"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2023\/02\/chic-chic-white.webp","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.gentleaf.com\/prodotto\/chic-chic-scrunchies-white-dragon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gentleaf.com\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.gentleaf.com\/es\/shop\/"},{"@type":"ListItem","position":3,"name":"CHIC CHIC Scrunchies &#8211; White Dragon"}]},{"@type":"WebSite","@id":"https:\/\/www.gentleaf.com\/#website","url":"https:\/\/www.gentleaf.com\/","name":"Gentleaf","description":"Organic professional cosmetics","publisher":{"@id":"https:\/\/www.gentleaf.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gentleaf.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gentleaf.com\/#organization","name":"Gentleaf","url":"https:\/\/www.gentleaf.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gentleaf.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2024\/02\/biogentleaf-logo-head.svg","contentUrl":"https:\/\/www.gentleaf.com\/wp-content\/uploads\/2024\/02\/biogentleaf-logo-head.svg","width":100,"height":100,"caption":"Gentleaf"},"image":{"@id":"https:\/\/www.gentleaf.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/gentleaf_bio\/?fbclid=IwY2xjawKBnY5leHRuA2FlbQIxMABicmlkETFnR3FwYjZ4RGRtRFJjamp2AR4SGdGOPrfdrVW-SGgGqLeTEuWwIANOXw19d6-WwnRUnESn5A7nOSsg73FS5A_aem_8xfPJYhVFMj_7_V1SzFGbg"]}]}},"brands":[{"id":171,"name":"Korean HCR","slug":"korean-hcr"}],"_links":{"self":[{"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/product\/2195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/media\/2196"}],"wp:attachment":[{"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/media?parent=2195"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/pwb-brand?post=2195"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/product_brand?post=2195"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/product_cat?post=2195"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.gentleaf.com\/es\/wp-json\/wp\/v2\/product_tag?post=2195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}